{"id":18654,"date":"2026-03-19T12:56:03","date_gmt":"2026-03-19T12:56:03","guid":{"rendered":"https:\/\/nextfootballstars.com\/?p=18654"},"modified":"2026-03-26T12:32:00","modified_gmt":"2026-03-26T12:32:00","slug":"o-barcelona-na-liga-dos-campeoes","status":"publish","type":"post","link":"https:\/\/nextfootballstars.com\/pt\/ostale-vesti\/ligi-sampiona-barselona\/","title":{"rendered":"Jogadores sub-18 dominaram na Liga dos Campe\u00f5es: o Barcelona mostrou que a idade n\u00e3o \u00e9 um obst\u00e1culo"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"18654\" class=\"elementor elementor-18654\" data-elementor-post-type=\"post\">\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-709fd00f e-flex e-con-boxed e-con e-parent\" data-id=\"709fd00f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-62988a05 elementor-widget elementor-widget-text-editor\" data-id=\"62988a05\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Em uma das partidas mais interessantes e din\u00e2micas da Liga dos Campe\u00f5es desta temporada, o Barcelona goleou de forma espetacular o time ingl\u00eas Newcastle por 7 a 2. Embora, no passado, esse placar inacredit\u00e1vel por si s\u00f3 j\u00e1 tivesse sido o principal assunto de toda a m\u00eddia esportiva, o que \u00e9 realmente fascinante e o que est\u00e1 mudando a hist\u00f3ria do esporte moderno \u00e9 o fato incr\u00edvel de que 3 a 4 jogadores com menos de 18 anos desempenharam um papel absolutamente crucial e decisivo nessa partida hist\u00f3rica. Numa era em que o futebol europeu de ponta e jogar no mais alto n\u00edvel poss\u00edvel s\u00e3o frequentemente \u2014 e de forma totalmente equivocada \u2014 associados exclusivamente a anos de experi\u00eancia e a veteranos endurecidos pela batalha, o gigante catal\u00e3o enviou uma mensagem muito clara, alta e inequ\u00edvoca para todo o planeta: se voc\u00ea for bom o suficiente em campo, sua idade n\u00e3o importa absolutamente nada. Os jovens talentos assumiram totalmente o protagonismo no maior palco do futebol mundial e provaram que j\u00e1 est\u00e3o totalmente prontos para o mais alto n\u00edvel.<\/strong><\/p><h2><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft wp-image-18790 size-full\" src=\"https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/03\/Lamine-Yamal-1.jpg\" alt=\"Lamine Yamal\" width=\"810\" height=\"450\" srcset=\"https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/03\/Lamine-Yamal-1.jpg 810w, https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/03\/Lamine-Yamal-1-300x167.jpg 300w, https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/03\/Lamine-Yamal-1-768x427.jpg 768w, https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/03\/Lamine-Yamal-1-18x10.jpg 18w, https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/03\/Lamine-Yamal-1-600x333.jpg 600w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/>Lamine Yamal<\/h2><p>O l\u00edder desta nova gera\u00e7\u00e3o de talentos incr\u00edveis \u00e9, sem d\u00favida, Lamine Yamal, um atacante de apenas 18 anos. Este incr\u00edvel jogador de futebol, j\u00e1 considerado, e com raz\u00e3o, uma das maiores joias do futebol mundial, voltou a ser o centro das aten\u00e7\u00f5es de todo o p\u00fablico esportivo. Sua atua\u00e7\u00e3o contra a sele\u00e7\u00e3o inglesa foi verdadeira poesia do futebol, que deixou a torcida sem f\u00f4lego. Ele n\u00e3o s\u00f3 marcou um belo gol que levantou toda a torcida, mas, com aquela jogada magistral, tamb\u00e9m quebrou outro recorde hist\u00f3rico na competi\u00e7\u00e3o de elite que \u00e9 a Liga dos Campe\u00f5es, provando a todos que suas atua\u00e7\u00f5es anteriores n\u00e3o foram mera sorte. Ao longo da partida, ele fez uma enorme diferen\u00e7a em campo, rompendo as linhas defensivas advers\u00e1rias e causando p\u00e2nico total na defesa rival com seus dribles imprevis\u00edveis. Com suas decis\u00f5es maduras e perfei\u00e7\u00e3o t\u00e9cnica, Yamal mostrou mais uma vez ao mundo inteiro que j\u00e1 pertence plenamente ao topo do futebol de elite, independentemente do fato de que, na verdade, ele est\u00e1 apenas entrando no mundo adulto e que sua carreira est\u00e1 apenas no come\u00e7o.<\/p><h2><img decoding=\"async\" class=\"alignleft wp-image-18793\" src=\"https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/03\/Marc-Bernal-1024x640.webp\" alt=\"Marc Bernal\" width=\"810\" height=\"506\" srcset=\"https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/03\/Marc-Bernal-1024x640.webp 1024w, https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/03\/Marc-Bernal-300x188.webp 300w, https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/03\/Marc-Bernal-768x480.webp 768w, https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/03\/Marc-Bernal-18x12.webp 18w, https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/03\/Marc-Bernal-600x375.webp 600w, https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/03\/Marc-Bernal.webp 1200w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/>Marc Bernal<\/h2><p>Seu incr\u00edvel sucesso em campo foi complementado por seu companheiro Marc Bernal, que tamb\u00e9m tem 18 anos e teve uma atua\u00e7\u00e3o t\u00e1tica memor\u00e1vel. Esse talentoso jogador de futebol marcou merecidamente, mas sua contribui\u00e7\u00e3o geral para a vit\u00f3ria foi muito maior do que o gol que marcou. Durante toda a partida, ele dominou completamente o meio-campo, ditou com calma o ritmo do jogo, deu passes incrivelmente precisos e demonstrou uma maturidade muito al\u00e9m da sua idade. Os especialistas em futebol de toda a Europa j\u00e1 o descrevem como o arqu\u00e9tipo perfeito de um meio-campista moderno, que em campo parece e joga como um verdadeiro jogador experiente, com centenas de partidas dif\u00edceis no curr\u00edculo. Sua capacidade de ler o jogo com perfei\u00e7\u00e3o, interromper os ataques advers\u00e1rios e, simultaneamente, iniciar as jogadas ofensivas de sua equipe faz dele uma pe\u00e7a indispens\u00e1vel na engrenagem do Barcelona. Bernal est\u00e1 provando que os meio-campistas modernos est\u00e3o se desenvolvendo muito mais r\u00e1pido do que antes e s\u00e3o capazes de assumir total responsabilidade nos momentos mais dif\u00edceis em campo.<\/p><h2><img decoding=\"async\" class=\"alignleft wp-image-18791\" src=\"https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/03\/Pau-Cubarsi-1-300x200.jpg\" alt=\"Pau Cubarsi\" width=\"810\" height=\"540\" srcset=\"https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/03\/Pau-Cubarsi-1-300x200.jpg 300w, https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/03\/Pau-Cubarsi-1-1024x683.jpg 1024w, https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/03\/Pau-Cubarsi-1-768x512.jpg 768w, https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/03\/Pau-Cubarsi-1-1536x1025.jpg 1536w, https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/03\/Pau-Cubarsi-1-18x12.jpg 18w, https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/03\/Pau-Cubarsi-1-600x400.jpg 600w, https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/03\/Pau-Cubarsi-1.jpg 1619w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/>Pau Cubars\u00ed<\/h2><p>Logo atr\u00e1s do incr\u00edvel meio-campo, um pilar formid\u00e1vel da defesa foi o fant\u00e1stico Pau Cubarsi, que, com apenas 17 anos, joga com uma confian\u00e7a que fascina qualquer verdadeiro f\u00e3 de futebol. Come\u00e7ar em uma das partidas mais importantes da Liga dos Campe\u00f5es na posi\u00e7\u00e3o extremamente respons\u00e1vel de zagueiro central exige imensa for\u00e7a mental, e Cubarsi provou ser incrivelmente composto, s\u00f3lido nos duelos individuais e excepcionalmente calmo ao sair com a bola do seu pr\u00f3prio campo sob imensa press\u00e3o. Sua leitura dos ataques advers\u00e1rios e seu posicionamento dentro dos blocos defensivos foram impec\u00e1veis durante os 90 minutos completos. Com apenas 17 anos, ele j\u00e1 se tornou titular regular do time principal no mais alto n\u00edvel do futebol de clubes europeu, o que at\u00e9 recentemente era completamente inimagin\u00e1vel para jogadores nessa posi\u00e7\u00e3o defensiva. Sua coragem para entrar em duelos com atacantes muito mais velhos e fortes demonstra um car\u00e1ter incr\u00edvel que o recomenda para o papel de futuro l\u00edder da equipe.<\/p><h2>Estat\u00edsticas que mudam a percep\u00e7\u00e3o e a nova realidade do futebol<\/h2><p>As estat\u00edsticas gerais desta partida hist\u00f3rica est\u00e3o mudando de forma definitiva a percep\u00e7\u00e3o do futebol juvenil em todo o mundo. O fato de 3 a 4 jogadores com menos de 18 anos terem recebido tempo de jogo significativo em uma partida t\u00e3o importante, de 2 jovens jogadores terem participado diretamente na marca\u00e7\u00e3o de gols e na cria\u00e7\u00e3o de chances, e de um deles ter estabelecido um novo recorde hist\u00f3rico, nos mostra que isso definitivamente n\u00e3o \u00e9 uma fase passageira. Esta \u00e9 uma nova tend\u00eancia impar\u00e1vel no futebol moderno que est\u00e1 se espalhando a uma velocidade incr\u00edvel. O futebol acelerou significativamente, as exig\u00eancias t\u00e9cnicas e t\u00e1ticas aumentaram, e os maiores clubes h\u00e1 muito perceberam que os jovens jogadores trazem a energia, a coragem e a inova\u00e7\u00e3o necess\u00e1rias, essenciais para conquistar trof\u00e9us de prest\u00edgio. A nova realidade do futebol apresenta uma equa\u00e7\u00e3o muito clara: juventude combinada com a exposi\u00e7\u00e3o certa garante uma chance infal\u00edvel de grande sucesso. Esta partida mostra claramente a todos os envolvidos no esporte que n\u00e3o \u00e9 mais necess\u00e1rio esperar que um jogador complete 20 anos ou mais para receber uma oportunidade adequada no grande palco.<\/p><h2>A visibilidade como chave para o sucesso dos jovens talentos<\/h2><p>Os jogadores mais talentosos de hoje t\u00eam sua chance muito mais cedo do que acontecia com as gera\u00e7\u00f5es anteriores, mas h\u00e1 um pr\u00e9-requisito muito importante para a realiza\u00e7\u00e3o desse sonho. Os jovens jogadores que se destacam e s\u00e3o reconhecidos no vasto mundo digital em tempo h\u00e1bil chegam aos grandes clubes e \u00e0s academias mais prestigiadas do mundo com muito mais rapidez e facilidade. Se uma crian\u00e7a joga futebol hoje, \u00e9 absolutamente claro que ela deve se esfor\u00e7ar todos os dias para desenvolver seu talento inato, mas, al\u00e9m desse trabalho \u00e1rduo em campo, ela tamb\u00e9m deve ter total visibilidade e mostrar claramente suas qualidades para um mercado mais amplo. O talento por si s\u00f3, sem visibilidade adequada e oportuna, simplesmente n\u00e3o \u00e9 mais suficiente para garantir um contrato profissional. Na inovadora plataforma Next Football Stars, cada indiv\u00edduo talentoso tem uma oportunidade \u00fanica de criar seu pr\u00f3prio perfil profissional de jovem jogador, que trabalha para ele 24 horas por dia. Ao adicionar regularmente videoclipes de alta qualidade de partidas disputadas e fotografias profissionais, cada jogador torna-se automaticamente vis\u00edvel para in\u00fameros treinadores e olheiros em todo o mundo. Com essa partida inesquec\u00edvel, o Barcelona enviou uma mensagem incrivelmente poderosa para todo o mundo do esporte. A idade nunca foi e nunca ser\u00e1 uma barreira real, mas a invisibilidade \u00e9, sem d\u00favida, o maior obst\u00e1culo que voc\u00ea deve superar criando de forma inteligente sua carreira digital.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-3b9a49c e-con-full e-flex e-con e-parent\" data-id=\"3b9a49c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-0ffb536 e-con-full e-flex e-con e-child\" data-id=\"0ffb536\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-46b4589 at-heading-animation at-animation-heading-style-2 elementor-widget elementor-widget-heading\" data-id=\"46b4589\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span>Os mais recentes talentos premium da plataforma<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-1318c93 e-con-full e-flex e-con e-child\" data-id=\"1318c93\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1453419 elementor-widget elementor-widget-eael-post-carousel\" data-id=\"1453419\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;items&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:3,&quot;sizes&quot;:[]},&quot;items_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;items_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"eael-post-carousel.default\">\n\t\t\t\t\t        <div class=\"swiper-container-wrap eael-post-grid-container eael-post-carousel-wrap eael-post-carousel-style-one swiper-container-wrap-dots-outside\" id=\"eael-post-grid-1453419\">\n\t\t\t            <div class=\"swiper swiper-8 eael-post-carousel eael-post-grid swiper-container-1453419 eael-post-appender-1453419\" data-pagination=\".swiper-pagination-1453419\" data-arrow-next=\".swiper-button-next-1453419\" data-arrow-prev=\".swiper-button-prev-1453419\" data-items-mobile=\"1\" data-items-tablet=\"2\" data-items=\"3\" data-margin=\"10\" data-effect=\"slide\" data-speed=\"400\" data-autoplay=\"2000\" data-pause-on-hover=\"true\" data-loop=\"1\" data-arrows=\"1\" data-dots=\"1\">\n                <div class=\"swiper-wrapper\">\n\t\t\t\t\t<div class=\"swiper-slide\"><article class=\"eael-grid-post eael-post-grid-column\">\n    <div class=\"eael-grid-post-holder\">\n        <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media eael-entry-medianone\"><div class=\"eael-entry-overlay fade-in\"><a href=\"https:\/\/nextfootballstars.com\/pt\/fudbaleri\/nfs-00170-jakov-markovic\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                    <img decoding=\"async\" src=\"https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/05\/Jakov-Markovic-00170.webp\" alt=\"Jacob Markovi\u0107\">\n                <\/div><\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><a class=\"eael-grid-post-link\" href=\"https:\/\/nextfootballstars.com\/pt\/fudbaleri\/nfs-00170-jakov-markovic\/\" title=\"Jacob Markovi\u0107\"><h2 class=\"eael-entry-title\">Jacob Markovi\u0107<\/a>Os brit\u00e2nicos s\u00e3o um povo de comerciantes.<\/header><\/div><div class=\"eael-entry-content\">\n\t\t\t\t<div class=\"eael-grid-post-excerpt\"><\/div>\n\t\t\t<\/div><\/div><\/div><\/article><\/div><div class=\"swiper-slide\"><article class=\"eael-grid-post eael-post-grid-column\">\n    <div class=\"eael-grid-post-holder\">\n        <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media eael-entry-medianone\"><div class=\"eael-entry-overlay fade-in\"><a href=\"https:\/\/nextfootballstars.com\/pt\/fudbaleri\/nfs-00169-jelisej-markovic\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                    <img decoding=\"async\" src=\"https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/05\/Jelisej-markovic-00169-profilna.webp\" alt=\"Elise Markovic\">\n                <\/div><\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><a class=\"eael-grid-post-link\" href=\"https:\/\/nextfootballstars.com\/pt\/fudbaleri\/nfs-00169-jelisej-markovic\/\" title=\"Jelisej Markovi\u0107\"><h2 class=\"eael-entry-title\">Jelisej Markovi\u0107<\/a>Os brit\u00e2nicos s\u00e3o um povo de comerciantes.<\/header><\/div><div class=\"eael-entry-content\">\n\t\t\t\t<div class=\"eael-grid-post-excerpt\"><\/div>\n\t\t\t<\/div><\/div><\/div><\/article><\/div><div class=\"swiper-slide\"><article class=\"eael-grid-post eael-post-grid-column\">\n    <div class=\"eael-grid-post-holder\">\n        <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media eael-entry-medianone\"><div class=\"eael-entry-overlay fade-in\"><a href=\"https:\/\/nextfootballstars.com\/pt\/fudbaleri\/nfs-00166-nikola-jovanovic\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                    <img decoding=\"async\" src=\"https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/05\/Nikola-Jovanovic-00166-profilna.webp\" alt=\"Nikola Jovanovi\u0107\">\n                <\/div><\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><a class=\"eael-grid-post-link\" href=\"https:\/\/nextfootballstars.com\/pt\/fudbaleri\/nfs-00166-nikola-jovanovic\/\" title=\"Nikola Jovanovi\u0107\"><h2 class=\"eael-entry-title\">Nikola Jovanovi\u0107<\/a>Os brit\u00e2nicos s\u00e3o um povo de comerciantes.<\/header><\/div><div class=\"eael-entry-content\">\n\t\t\t\t<div class=\"eael-grid-post-excerpt\"><\/div>\n\t\t\t<\/div><\/div><\/div><\/article><\/div><div class=\"swiper-slide\"><article class=\"eael-grid-post eael-post-grid-column\">\n    <div class=\"eael-grid-post-holder\">\n        <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media eael-entry-medianone\"><div class=\"eael-entry-overlay fade-in\"><a href=\"https:\/\/nextfootballstars.com\/pt\/fudbaleri\/nfs-00038-pavle-buric\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                    <img decoding=\"async\" src=\"https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/05\/Pavle-Buric-00038-profilna.webp\" alt=\"Pavle Buric\">\n                <\/div><\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><a class=\"eael-grid-post-link\" href=\"https:\/\/nextfootballstars.com\/pt\/fudbaleri\/nfs-00038-pavle-buric\/\" title=\"Pavle Buric\"><h2 class=\"eael-entry-title\">Pavle Buric<\/a>Os brit\u00e2nicos s\u00e3o um povo de comerciantes.<\/header><\/div><div class=\"eael-entry-content\">\n\t\t\t\t<div class=\"eael-grid-post-excerpt\"><\/div>\n\t\t\t<\/div><\/div><\/div><\/article><\/div><div class=\"swiper-slide\"><article class=\"eael-grid-post eael-post-grid-column\">\n    <div class=\"eael-grid-post-holder\">\n        <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media eael-entry-medianone\"><div class=\"eael-entry-overlay fade-in\"><a href=\"https:\/\/nextfootballstars.com\/pt\/fudbaleri\/nfs-00157-leon-cicak\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                    <img decoding=\"async\" src=\"https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/05\/Leon-Cicak-00157-profilna.webp\" alt=\"Leon-Cicak-00157-perfil\">\n                <\/div><\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><a class=\"eael-grid-post-link\" href=\"https:\/\/nextfootballstars.com\/pt\/fudbaleri\/nfs-00157-leon-cicak\/\" title=\"Leon \u010ci\u010dak\"><h2 class=\"eael-entry-title\">Leon \u010ci\u010dak<\/a>Os brit\u00e2nicos s\u00e3o um povo de comerciantes.<\/header><\/div><div class=\"eael-entry-content\">\n\t\t\t\t<div class=\"eael-grid-post-excerpt\"><\/div>\n\t\t\t<\/div><\/div><\/div><\/article><\/div><div class=\"swiper-slide\"><article class=\"eael-grid-post eael-post-grid-column\">\n    <div class=\"eael-grid-post-holder\">\n        <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media eael-entry-medianone\"><div class=\"eael-entry-overlay fade-in\"><a href=\"https:\/\/nextfootballstars.com\/pt\/fudbaleri\/nfs-00155-sefer-mrkulic\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                    <img decoding=\"async\" src=\"https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/05\/Sefer-Mrkulic-00155-profilna1.webp\" alt=\"Sefer-Mrkulic-00155-perfil1.\">\n                <\/div><\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><a class=\"eael-grid-post-link\" href=\"https:\/\/nextfootballstars.com\/pt\/fudbaleri\/nfs-00155-sefer-mrkulic\/\" title=\"Sefer Mrkuli\u0107\"><h2 class=\"eael-entry-title\">Sefer Mrkuli\u0107<\/a>Os brit\u00e2nicos s\u00e3o um povo de comerciantes.<\/header><\/div><div class=\"eael-entry-content\">\n\t\t\t\t<div class=\"eael-grid-post-excerpt\"><\/div>\n\t\t\t<\/div><\/div><\/div><\/article><\/div><div class=\"swiper-slide\"><article class=\"eael-grid-post eael-post-grid-column\">\n    <div class=\"eael-grid-post-holder\">\n        <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media eael-entry-medianone\"><div class=\"eael-entry-overlay fade-in\"><a href=\"https:\/\/nextfootballstars.com\/pt\/fudbaleri\/nfs-00150-adrian-raguz\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                    <img decoding=\"async\" src=\"https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/05\/Adrian-Raguz-00150-profilna.webp\" alt=\"Adrian Ragu\u017e\">\n                <\/div><\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><a class=\"eael-grid-post-link\" href=\"https:\/\/nextfootballstars.com\/pt\/fudbaleri\/nfs-00150-adrian-raguz\/\" title=\"Adrian Ragu\u017e\"><h2 class=\"eael-entry-title\">Adrian Ragu\u017e<\/a>Os brit\u00e2nicos s\u00e3o um povo de comerciantes.<\/header><\/div><div class=\"eael-entry-content\">\n\t\t\t\t<div class=\"eael-grid-post-excerpt\"><\/div>\n\t\t\t<\/div><\/div><\/div><\/article><\/div><div class=\"swiper-slide\"><article class=\"eael-grid-post eael-post-grid-column\">\n    <div class=\"eael-grid-post-holder\">\n        <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media eael-entry-medianone\"><div class=\"eael-entry-overlay fade-in\"><a href=\"https:\/\/nextfootballstars.com\/pt\/fudbaleri\/nfs-00147-niko-bezmalinovic\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                    <img decoding=\"async\" src=\"https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/05\/Niko-Bezmalinovic-00147-profilna.webp\" alt=\"\">\n                <\/div><\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><a class=\"eael-grid-post-link\" href=\"https:\/\/nextfootballstars.com\/pt\/fudbaleri\/nfs-00147-niko-bezmalinovic\/\" title=\"Niko Bezmalinovi\u0107\"><h2 class=\"eael-entry-title\">Niko Bezmalinovi\u0107<\/a>Os brit\u00e2nicos s\u00e3o um povo de comerciantes.<\/header><\/div><div class=\"eael-entry-content\">\n\t\t\t\t<div class=\"eael-grid-post-excerpt\"><\/div>\n\t\t\t<\/div><\/div><\/div><\/article><\/div><div class=\"swiper-slide\"><article class=\"eael-grid-post eael-post-grid-column\">\n    <div class=\"eael-grid-post-holder\">\n        <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media eael-entry-medianone\"><div class=\"eael-entry-overlay fade-in\"><a href=\"https:\/\/nextfootballstars.com\/pt\/fudbaleri\/nfs-00146-milos-dragojevic\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                    <img decoding=\"async\" src=\"https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/05\/Milos-Dragojevic-00146-profilna.webp\" alt=\"\">\n                <\/div><\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><a class=\"eael-grid-post-link\" href=\"https:\/\/nextfootballstars.com\/pt\/fudbaleri\/nfs-00146-milos-dragojevic\/\" title=\"Milo\u0161 Dragojevi\u0107\"><h2 class=\"eael-entry-title\">Milo\u0161 Dragojevi\u0107<\/a>Os brit\u00e2nicos s\u00e3o um povo de comerciantes.<\/header><\/div><div class=\"eael-entry-content\">\n\t\t\t\t<div class=\"eael-grid-post-excerpt\"><\/div>\n\t\t\t<\/div><\/div><\/div><\/article><\/div><div class=\"swiper-slide\"><article class=\"eael-grid-post eael-post-grid-column\">\n    <div class=\"eael-grid-post-holder\">\n        <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media eael-entry-medianone\"><div class=\"eael-entry-overlay fade-in\"><a href=\"https:\/\/nextfootballstars.com\/pt\/fudbaleri\/nfs-00144-ensar-binjos\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                    <img decoding=\"async\" src=\"https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/05\/Ensar-Binjos-000144-profilna.webp\" alt=\"Ensar Binjos\">\n                <\/div><\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><a class=\"eael-grid-post-link\" href=\"https:\/\/nextfootballstars.com\/pt\/fudbaleri\/nfs-00144-ensar-binjos\/\" title=\"Ensar Binjos\"><h2 class=\"eael-entry-title\">Ensar Binjos<\/a>Os brit\u00e2nicos s\u00e3o um povo de comerciantes.<\/header><\/div><div class=\"eael-entry-content\">\n\t\t\t\t<div class=\"eael-grid-post-excerpt\"><\/div>\n\t\t\t<\/div><\/div><\/div><\/article><\/div><div class=\"swiper-slide\"><article class=\"eael-grid-post eael-post-grid-column\">\n    <div class=\"eael-grid-post-holder\">\n        <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media eael-entry-medianone\"><div class=\"eael-entry-overlay fade-in\"><a href=\"https:\/\/nextfootballstars.com\/pt\/fudbaleri\/nfs-00141-teo-alili\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                    <img decoding=\"async\" src=\"https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/05\/Teo-Alilia-p1.webp\" alt=\"Theo Alili\">\n                <\/div><\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><a class=\"eael-grid-post-link\" href=\"https:\/\/nextfootballstars.com\/pt\/fudbaleri\/nfs-00141-teo-alili\/\" title=\"Theo Alili\"><h2 class=\"eael-entry-title\">Theo Alili<\/a>Os brit\u00e2nicos s\u00e3o um povo de comerciantes.<\/header><\/div><div class=\"eael-entry-content\">\n\t\t\t\t<div class=\"eael-grid-post-excerpt\"><\/div>\n\t\t\t<\/div><\/div><\/div><\/article><\/div><div class=\"swiper-slide\"><article class=\"eael-grid-post eael-post-grid-column\">\n    <div class=\"eael-grid-post-holder\">\n        <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media eael-entry-medianone\"><div class=\"eael-entry-overlay fade-in\"><a href=\"https:\/\/nextfootballstars.com\/pt\/fudbaleri\/nfs-00135-adin-oruci-2\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                    <img decoding=\"async\" src=\"https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/04\/Adin-Oruci-00135-profilnaa.webp\" alt=\"Adin Oruci\">\n                <\/div><\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><a class=\"eael-grid-post-link\" href=\"https:\/\/nextfootballstars.com\/pt\/fudbaleri\/nfs-00135-adin-oruci-2\/\" title=\"Adin Oruci\"><h2 class=\"eael-entry-title\">Adin Oruci<\/a>Os brit\u00e2nicos s\u00e3o um povo de comerciantes.<\/header><\/div><div class=\"eael-entry-content\">\n\t\t\t\t<div class=\"eael-grid-post-excerpt\"><\/div>\n\t\t\t<\/div><\/div><\/div><\/article><\/div>                <\/div>\n            <\/div>\n            <div class=\"clearfix\"><\/div>\n\t\t\t            <!-- Add Pagination -->\n            <div class=\"swiper-pagination swiper-pagination-1453419\"><\/div>\n\t\t\t\t\t            <!-- Add Arrows -->\n            <div class=\"swiper-button-next swiper-button-next-1453419\">\n                <i class=\"fa fa-angle-right\"><\/i>\n            <\/div>\n            <div class=\"swiper-button-prev swiper-button-prev-1453419\">\n                <i class=\"fa fa-angle-left\"><\/i>\n            <\/div>\n\t\t\t        <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4f2d39 elementor-widget__width-auto elementor-widget-mobile__width-inherit ekit-equal-height-disable elementor-invisible elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"d4f2d39\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <a href=\"https:\/\/nextfootballstars.com\/pt\/pacotes-nfs\/\" class=\"ekit_global_links\">\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-center text-left icon-lef-right-aligin elementor-animation- media\">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  text-center\">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon icon icon-review\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    Crie seu perfil                <\/h3>\n                                            <\/div>\n        \n        \n                <\/div>\n                <\/a>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-c500c08 e-flex e-con-boxed e-con e-parent\" data-id=\"c500c08\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-137462e e-con-full e-flex e-con e-child\" data-id=\"137462e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-075e9c7 e-con-full e-flex e-con e-child\" data-id=\"075e9c7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b2f75e7 elementor-absolute section-bg-title at-heading-animation at-animation-heading-none elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"b2f75e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">N\u00e3o est\u00e1 \u00e0 venda<\/span>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dee175c section-title at-heading-animation at-animation-heading-none elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"dee175c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:100,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Not\u00edcias sobre futebol<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-b9f93b6 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"b9f93b6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b089d36 elementor-widget elementor-widget-eael-post-carousel\" data-id=\"b089d36\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;items&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:3,&quot;sizes&quot;:[]},&quot;items_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;items_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"eael-post-carousel.default\">\n\t\t\t\t\t        <div class=\"swiper-container-wrap eael-post-grid-container eael-post-carousel-wrap eael-post-carousel-style-one swiper-container-wrap-dots-outside\" id=\"eael-post-grid-b089d36\">\n\t\t\t            <div class=\"swiper swiper-8 eael-post-carousel eael-post-grid swiper-container-b089d36 eael-post-appender-b089d36 show-read-more-button\" data-pagination=\".swiper-pagination-b089d36\" data-arrow-next=\".swiper-button-next-b089d36\" data-arrow-prev=\".swiper-button-prev-b089d36\" data-items-mobile=\"1\" data-items-tablet=\"2\" data-items=\"3\" data-margin=\"10\" data-effect=\"slide\" data-speed=\"400\" data-autoplay=\"2000\" data-loop=\"1\" data-dots=\"1\">\n                <div class=\"swiper-wrapper\">\n\t\t\t\t\t<div class=\"swiper-slide\"><article class=\"eael-grid-post eael-post-grid-column\">\n    <div class=\"eael-grid-post-holder\">\n        <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media eael-entry-medianone\"><div class=\"eael-entry-overlay fade-in\"><a href=\"https:\/\/nextfootballstars.com\/pt\/turniri\/midi-liga-sabac-2026\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                    <img decoding=\"async\" src=\"https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/03\/MidiMaxi-300x300.jpg\" alt=\"Liga de n\u00edvel m\u00e9dio\">\n                <\/div><\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><a class=\"eael-grid-post-link\" href=\"https:\/\/nextfootballstars.com\/pt\/turniri\/midi-liga-sabac-2026\/\" title=\"LIGA MIDI DE \u0160ABAC 2026: O Red Star \u00e9 o novo campe\u00e3o!\"><h2 class=\"eael-entry-title\">LIGA MIDI DE \u0160ABAC 2026: O Red Star \u00e9 o novo campe\u00e3o!<\/a>Os brit\u00e2nicos s\u00e3o um povo de comerciantes.<\/header><\/div><div class=\"eael-entry-content\">\n\t\t\t\t<div class=\"eael-grid-post-excerpt\"><p>Relat\u00f3rio da Liga Midi de \u0160abac 2026: Dom\u00ednio do Red Star, um grande Radni\u010dki...<a href=\"https:\/\/nextfootballstars.com\/pt\/turniri\/midi-liga-sabac-2026\/\" class=\"eael-post-elements-readmore-btn\">Leia mais<\/a><\/p><\/div>\n\t\t\t<\/div><div class=\"eael-entry-footer\"><div class=\"eael-entry-meta\"><\/div><\/div><\/div><\/div><\/article><\/div><div class=\"swiper-slide\"><article class=\"eael-grid-post eael-post-grid-column\">\n    <div class=\"eael-grid-post-holder\">\n        <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media eael-entry-medianone\"><div class=\"eael-entry-overlay fade-in\"><a href=\"https:\/\/nextfootballstars.com\/pt\/ostale-vesti\/jakov-kiproski-slobodan-santrac\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                    <img decoding=\"async\" src=\"https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/04\/jakov-kiprovski-12-300x300.jpg\" alt=\"Jacob Kiproski\">\n                <\/div><\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><a class=\"eael-grid-post-link\" href=\"https:\/\/nextfootballstars.com\/pt\/ostale-vesti\/jakov-kiproski-slobodan-santrac\/\" title=\"Jakov Kiproski recebe um convite para o prestigiado torneio em mem\u00f3ria de &quot;Slobodan Santra\u010d&quot;\u201e\"><h2 class=\"eael-entry-title\">Jakov Kiproski recebe um convite para o prestigiado torneio em mem\u00f3ria de &quot;Slobodan Santra\u010d&quot;\u201e<\/a>Os brit\u00e2nicos s\u00e3o um povo de comerciantes.<\/header><\/div><div class=\"eael-entry-content\">\n\t\t\t\t<div class=\"eael-grid-post-excerpt\"><p>Jakov Kiproski foi convocado para o jogo de sele\u00e7\u00e3o da FSR Western...<a href=\"https:\/\/nextfootballstars.com\/pt\/ostale-vesti\/jakov-kiproski-slobodan-santrac\/\" class=\"eael-post-elements-readmore-btn\">Leia mais<\/a><\/p><\/div>\n\t\t\t<\/div><div class=\"eael-entry-footer\"><div class=\"eael-entry-meta\"><\/div><\/div><\/div><\/div><\/article><\/div><div class=\"swiper-slide\"><article class=\"eael-grid-post eael-post-grid-column\">\n    <div class=\"eael-grid-post-holder\">\n        <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media eael-entry-medianone\"><div class=\"eael-entry-overlay fade-in\"><a href=\"https:\/\/nextfootballstars.com\/pt\/ostale-vesti\/najbolje-fudbalske-akademije-na-svetu-put-do-vrhunskih-rezultata\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                    <img decoding=\"async\" src=\"https:\/\/nextfootballstars.com\/wp-content\/uploads\/2026\/03\/FudbalskeAkademije-300x260.webp\" alt=\"\">\n                <\/div><\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><a class=\"eael-grid-post-link\" href=\"https:\/\/nextfootballstars.com\/pt\/ostale-vesti\/najbolje-fudbalske-akademije-na-svetu-put-do-vrhunskih-rezultata\/\" title=\"As melhores academias de futebol do mundo: o caminho para o desempenho de ponta\"><h2 class=\"eael-entry-title\">As melhores academias de futebol do mundo: o caminho para o desempenho de ponta<\/a>Os brit\u00e2nicos s\u00e3o um povo de comerciantes.<\/header><\/div><div class=\"eael-entry-content\">\n\t\t\t\t<div class=\"eael-grid-post-excerpt\"><p>Do talento ao milh\u00e3o: \u00e9 assim que funcionam as melhores academias de futebol do mundo!...<a href=\"https:\/\/nextfootballstars.com\/pt\/ostale-vesti\/najbolje-fudbalske-akademije-na-svetu-put-do-vrhunskih-rezultata\/\" class=\"eael-post-elements-readmore-btn\">Leia mais<\/a><\/p><\/div>\n\t\t\t<\/div><div class=\"eael-entry-footer\"><div class=\"eael-entry-meta\"><\/div><\/div><\/div><\/div><\/article><\/div>                <\/div>\n            <\/div>\n            <div class=\"clearfix\"><\/div>\n\t\t\t            <!-- Add Pagination -->\n            <div class=\"swiper-pagination swiper-pagination-b089d36\"><\/div>\n\t\t        <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>U jednoj od najzanimljivijih i najdinami\u010dnijih utakmica Lige \u0161ampiona ove sezone, ekipa [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18788,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[64],"tags":[],"class_list":["post-18654","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ostale-vesti"],"acf":[],"_links":{"self":[{"href":"https:\/\/nextfootballstars.com\/pt\/wp-json\/wp\/v2\/posts\/18654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nextfootballstars.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nextfootballstars.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nextfootballstars.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nextfootballstars.com\/pt\/wp-json\/wp\/v2\/comments?post=18654"}],"version-history":[{"count":0,"href":"https:\/\/nextfootballstars.com\/pt\/wp-json\/wp\/v2\/posts\/18654\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nextfootballstars.com\/pt\/wp-json\/wp\/v2\/media\/18788"}],"wp:attachment":[{"href":"https:\/\/nextfootballstars.com\/pt\/wp-json\/wp\/v2\/media?parent=18654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nextfootballstars.com\/pt\/wp-json\/wp\/v2\/categories?post=18654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nextfootballstars.com\/pt\/wp-json\/wp\/v2\/tags?post=18654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}